{"id":1582,"date":"2017-07-04T05:38:27","date_gmt":"2017-07-04T05:38:27","guid":{"rendered":"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/?page_id=1582"},"modified":"2026-08-25T14:33:26","modified_gmt":"2026-08-25T07:33:26","slug":"%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%ab%e0%b8%a5%e0%b8%b1%e0%b8%81","status":"publish","type":"page","link":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/","title":{"rendered":"\u0e22\u0e34\u0e19\u0e14\u0e35\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a (\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01)"},"content":{"rendered":"<div dir=\"auto\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/complain\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21754 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/04\/main-3.gif\" alt=\"\" width=\"1600\" height=\"150\" \/><\/a><\/div>\n<div class=\"wptb-container-legacy\" data-table-id=\"25139\">\n    <table class=\"wptb-preview-table wptb-element-main-table_setting-25139\" style=\"border-spacing: 3px 3px; border-collapse: collapse !important; min-width: 100%; border: 0px solid rgb(255, 255, 255); \" data-border-spacing-columns=\"3\" data-border-spacing-rows=\"3\" data-reconstraction=\"1\" data-wptb-table-directives=\"eyJpbm5lckJvcmRlcnMiOnsiYWN0aXZlIjoiYWxsIiwiYm9yZGVyV2lkdGgiOjAsImJvcmRlclJhZGl1c2VzIjp7ImFsbCI6MCwicm93IjowLCJjb2x1bW4iOjB9fX0=\" data-wptb-responsive-directives=\"eyJyZXNwb25zaXZlRW5hYmxlZCI6ZmFsc2UsInJlc3BvbnNpdmVNb2RlIjoiYXV0byIsInJlbGF0aXZlV2lkdGgiOiJ3aW5kb3ciLCJwcmVzZXJ2ZVJvd0NvbG9yIjpmYWxzZSwiaGVhZGVyRnVsbHlNZXJnZWQiOmZhbHNlLCJicmVha3BvaW50cyI6eyJkZXNrdG9wIjp7Im5hbWUiOiJkZXNrdG9wIiwid2lkdGgiOjEwMjR9LCJ0YWJsZXQiOnsibmFtZSI6InRhYmxldCIsIndpZHRoIjo3MDB9LCJtb2JpbGUiOnsibmFtZSI6Im1vYmlsZSIsIndpZHRoIjozNzV9fSwibW9kZU9wdGlvbnMiOnsiYXV0byI6eyJkaXNhYmxlZCI6eyJkZXNrdG9wIjpmYWxzZSwidGFibGV0IjpmYWxzZSwibW9iaWxlIjpmYWxzZX0sInRvcFJvd0FzSGVhZGVyIjp7ImRlc2t0b3AiOmZhbHNlLCJ0YWJsZXQiOnRydWUsIm1vYmlsZSI6dHJ1ZX0sInJlcGVhdE1lcmdlZEhlYWRlciI6eyJkZXNrdG9wIjp0cnVlLCJ0YWJsZXQiOnRydWUsIm1vYmlsZSI6dHJ1ZX0sInN0YXRpY1RvcFJvdyI6eyJkZXNrdG9wIjpmYWxzZSwidGFibGV0IjpmYWxzZSwibW9iaWxlIjpmYWxzZX0sImNlbGxTdGFja0RpcmVjdGlvbiI6eyJkZXNrdG9wIjoicm93IiwidGFibGV0Ijoicm93IiwibW9iaWxlIjoicm93In0sImNlbGxzUGVyUm93Ijp7ImRlc2t0b3AiOjEsInRhYmxldCI6MiwibW9iaWxlIjoxfX19fQ==\" data-wptb-cells-width-auto-count=\"2\" data-wptb-extra-styles=\"\" data-wptb-pro-pagination-top-row-header=\"false\" data-wptb-rows-per-page=\"10\" data-wptb-pro-search-top-row-header=\"false\" data-wptb-searchbar-position=\"left\" role=\"table\" data-table-columns=\"2\" data-wptb-table-alignment=\"center\" data-wptb-td-width-auto=\"120\" data-wptb-table-tds-sum-max-width=\"280\" data-wptb-header-background-color=\"#ffffff\" data-wptb-even-row-background-color=\"#ffffff\" data-wptb-odd-row-background-color=\"#ffffff\" ><tbody data-global-font-size=\"15\" ><tr  class=\"wptb-row \" style=\"background-color: #ffffff; \"><td class=\"wptb-cell \" colspan=\"1\" rowspan=\"1\" style=\"padding: 10px; border-width: 1px; border-color: rgb(0, 0, 0); border-style: solid; border-radius: 0px; \" data-y-index=\"0\" data-x-index=\"0\" data-wptb-css-td-auto-width=\"true\" data-wptb-css-td-auto-height=\"true\" data-wptb-cell-vertical-alignment=\"center\" ><div class=\"wptb-image-container wptb-ph-element wptb-element-image-1\" data-wptb-image-alignment=\"center\" data-wptb-image-size-relative=\"container\"  style=\"\">\n    <div class=\"wptb-image-wrapper\">\n        <a href=\"https:\/\/www.nacc.go.th\/allcomplaint\" target=\"_blank\"  class=\"wptb-link-target\" style=\"float: none; width: 100%; \">\n            <img loading=\"lazy\" decoding=\"async\" class=\"wptb-image-element-target\" data-wptb-size=\"377px:113px\" height=\"113\" width=\"377\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/05\/\u0e1b\u0e1b\u0e0a.gif\"  style=\"width: 100%\" \/>\n        <\/a>\n    <\/div>\n<\/div><\/td><td class=\"wptb-cell \" colspan=\"1\" rowspan=\"1\" style=\"padding: 10px; border-width: 1px; border-color: rgb(0, 0, 0); border-style: solid; border-radius: 0px; \" data-y-index=\"0\" data-x-index=\"1\" data-wptb-css-td-auto-width=\"true\" data-wptb-css-td-auto-height=\"true\" data-wptb-cell-vertical-alignment=\"center\" ><div class=\"wptb-image-container wptb-ph-element wptb-element-image-2\" data-wptb-image-alignment=\"center\" data-wptb-image-size-relative=\"container\"  style=\"\">\n    <div class=\"wptb-image-wrapper\">\n        <a href=\"https:\/\/anonymous.pacc.go.th\/\" target=\"_blank\"  class=\"wptb-link-target\" style=\"float: none; width: 100%; \">\n            <img loading=\"lazy\" decoding=\"async\" class=\"wptb-image-element-target\" data-wptb-size=\"0px:0px\" height=\"0\" width=\"0\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/05\/\u0e1b\u0e1b\u0e17.gif\"  style=\"width: 100%\" \/>\n        <\/a>\n    <\/div>\n<\/div><\/td><\/tr><\/tbody><\/table>\n<\/div>\n\n\n\n<table id=\"tablepress-21\" class=\"tablepress tablepress-id-21\">\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12537\" src=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png\" alt=\"\" width=\"25\" height=\"25\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png 365w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-840x840.png 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-768x768.png 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11.png 1000w\" sizes=\"auto, (max-width: 25px) 100vw, 25px\" \/> <a href=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/\" target=\"_blank\" rel=\"noopener\">\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u00a0<\/a><\/td><td class=\"column-2\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12537\" src=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png\" alt=\"\" width=\"25\" height=\"25\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png 365w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-840x840.png 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-768x768.png 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11.png 1000w\" sizes=\"auto, (max-width: 25px) 100vw, 25px\" \/> <a href=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/\" target=\"_blank\" rel=\"noopener\">\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/td><td class=\"column-3\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12537\" src=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png\" alt=\"\" width=\"25\" height=\"25\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png 365w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-840x840.png 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-768x768.png 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11.png 1000w\" sizes=\"auto, (max-width: 25px) 100vw, 25px\" \/><a href=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/\" target=\"_blank\" rel=\"noopener\">\u0e02\u0e48\u0e32\u0e27\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d-\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/td><td class=\"column-4\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12537\" src=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png\" alt=\"\" width=\"25\" height=\"25\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-365x365.png 365w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-840x840.png 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11-768x768.png 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2022\/01\/pnggate.com-11.png 1000w\" sizes=\"auto, (max-width: 25px) 100vw, 25px\" \/><a href=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/\" target=\"_blank\" rel=\"noopener\">\u0e02\u0e48\u0e32\u0e27\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-21 from cache -->\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8459 alignnone\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR2.jpg\" alt=\"\" width=\"804\" height=\"67\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR2.jpg 804w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR2-660x55.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR2-768x64.jpg 768w\" sizes=\"auto, (max-width: 804px) 100vw, 804px\" \/><\/p>\n<p><a style=\"transition-property: all;\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/\">\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a>\u00a0&gt; <div class=\"asl_w_container asl_w_container_1\" data-id=\"1\" data-instance=\"1\">\n\t<div id='ajaxsearchlite1'\n\t\tdata-id=\"1\"\n\t\tdata-instance=\"1\"\n\t\tclass=\"asl_w asl_m asl_m_1 asl_m_1_1\">\n\t\t<div class=\"probox\">\n\n\t\n\t<div class='prosettings' style='display:none;' data-opened=0>\n\t\t\t\t<div class='innericon'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<polygon transform = \"rotate(90 256 256)\" points=\"142.332,104.886 197.48,50 402.5,256 197.48,462 142.332,407.113 292.727,256 \"\/>\n\t\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/div>\n\n\t\n\t\n\t<div class='proinput'>\n\t\t<form role=\"search\" action='#' autocomplete=\"off\"\n\t\t\t\taria-label=\"Search form\">\n\t\t\t<input aria-label=\"Search input\"\n\t\t\t\t\ttype='search' class='orig'\n\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tplaceholder='Search here..'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\"\/>\n\t\t\t<input aria-label=\"Search autocomplete input\"\n\t\t\t\t\ttype='text'\n\t\t\t\t\tclass='autocomplete'\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\" disabled\/>\n\t\t\t<input type='submit' value=\"Start search\" style='width:0; height: 0; visibility: hidden;'>\n\t\t<\/form>\n\t<\/div>\n\n\t\n\t\n\t<button class='promagnifier' tabindex=\"0\" aria-label=\"Search magnifier button\">\n\t\t\t\t<span class='innericon' style=\"display:block;\">\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<path d=\"M460.355,421.59L353.844,315.078c20.041-27.553,31.885-61.437,31.885-98.037\n\t\t\t\t\t\tC385.729,124.934,310.793,50,218.686,50C126.58,50,51.645,124.934,51.645,217.041c0,92.106,74.936,167.041,167.041,167.041\n\t\t\t\t\t\tc34.912,0,67.352-10.773,94.184-29.158L419.945,462L460.355,421.59z M100.631,217.041c0-65.096,52.959-118.056,118.055-118.056\n\t\t\t\t\t\tc65.098,0,118.057,52.959,118.057,118.056c0,65.096-52.959,118.056-118.057,118.056C153.59,335.097,100.631,282.137,100.631,217.041\n\t\t\t\t\t\tz\"\/>\n\t\t\t\t<\/svg>\n\t\t<\/span>\n\t<\/button>\n\n\t\n\t\n\t<div class='proloading'>\n\n\t\t<div class=\"asl_loader\"><div class=\"asl_loader-inner asl_simple-circle\"><\/div><\/div>\n\n\t\t\t<\/div>\n\n\t\t\t<div class='proclose'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\"\n\t\t\t\ty=\"0px\"\n\t\t\t\twidth=\"12\" height=\"12\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\"\n\t\t\t\txml:space=\"preserve\">\n\t\t\t\t<polygon points=\"438.393,374.595 319.757,255.977 438.378,137.348 374.595,73.607 255.995,192.225 137.375,73.622 73.607,137.352 192.246,255.983 73.622,374.625 137.352,438.393 256.002,319.734 374.652,438.378 \"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\n\t\n<\/div>\t<\/div>\n\t<div class='asl_data_container' style=\"display:none !important;\">\n\t\t<div class=\"asl_init_data wpdreams_asl_data_ct\"\n\tstyle=\"display:none !important;\"\n\tid=\"asl_init_id_1\"\n\tdata-asl-id=\"1\"\n\tdata-asl-instance=\"1\"\n\tdata-settings=\"{&quot;homeurl&quot;:&quot;https:\\\/\\\/www.tasaban-maemoh.go.th\\\/tbmm\\\/&quot;,&quot;resultstype&quot;:&quot;vertical&quot;,&quot;resultsposition&quot;:&quot;hover&quot;,&quot;itemscount&quot;:4,&quot;charcount&quot;:0,&quot;minWordLength&quot;:2,&quot;highlight&quot;:false,&quot;highlightWholewords&quot;:true,&quot;singleHighlight&quot;:false,&quot;scrollToResults&quot;:{&quot;enabled&quot;:false,&quot;offset&quot;:0},&quot;resultareaclickable&quot;:1,&quot;autocomplete&quot;:{&quot;enabled&quot;:true,&quot;lang&quot;:&quot;en&quot;,&quot;trigger_charcount&quot;:0},&quot;mobile&quot;:{&quot;menu_selector&quot;:&quot;#menu-toggle&quot;},&quot;trigger&quot;:{&quot;click&quot;:&quot;results_page&quot;,&quot;click_location&quot;:&quot;same&quot;,&quot;update_href&quot;:false,&quot;return&quot;:&quot;results_page&quot;,&quot;return_location&quot;:&quot;same&quot;,&quot;facet&quot;:true,&quot;type&quot;:true,&quot;redirect_url&quot;:&quot;?s={phrase}&quot;,&quot;delay&quot;:300},&quot;animations&quot;:{&quot;pc&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;},&quot;mob&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;}},&quot;autop&quot;:{&quot;state&quot;:true,&quot;phrase&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;},&quot;resPage&quot;:{&quot;useAjax&quot;:false,&quot;selector&quot;:&quot;#main&quot;,&quot;trigger_type&quot;:true,&quot;trigger_facet&quot;:true,&quot;trigger_magnifier&quot;:false,&quot;trigger_return&quot;:false},&quot;resultsSnapTo&quot;:&quot;left&quot;,&quot;results&quot;:{&quot;width&quot;:&quot;auto&quot;,&quot;width_tablet&quot;:&quot;auto&quot;,&quot;width_phone&quot;:&quot;auto&quot;},&quot;settingsimagepos&quot;:&quot;left&quot;,&quot;closeOnDocClick&quot;:true,&quot;overridewpdefault&quot;:false,&quot;override_method&quot;:&quot;get&quot;}\"><\/div>\n\t<div id=\"asl_hidden_data\">\n\t\t<svg style=\"position:absolute\" height=\"0\" width=\"0\">\n\t\t\t<filter id=\"aslblur\">\n\t\t\t\t<feGaussianBlur in=\"SourceGraphic\" stdDeviation=\"4\"\/>\n\t\t\t<\/filter>\n\t\t<\/svg>\n\t\t<svg style=\"position:absolute\" height=\"0\" width=\"0\">\n\t\t\t<filter id=\"no_aslblur\"><\/filter>\n\t\t<\/svg>\n\t<\/div>\n\t<\/div>\n\n\t<div id='ajaxsearchliteres1'\n\tclass='vertical wpdreams_asl_results asl_w asl_r asl_r_1 asl_r_1_1'>\n\n\t\n\t<div class=\"results\">\n\n\t\t\n\t\t<div class=\"resdrg\">\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n\t\n<\/div>\n\n\t<div id='__original__ajaxsearchlitesettings1'\n\t\tdata-id=\"1\"\n\t\tclass=\"searchsettings wpdreams_asl_settings asl_w asl_s asl_s_1\">\n\t\t<form name='options'\n\t\taria-label=\"Search settings form\"\n\t\tautocomplete = 'off'>\n\n\t\n\t\n\t<input type=\"hidden\" name=\"filters_changed\" style=\"display:none;\" value=\"0\">\n\t<input type=\"hidden\" name=\"filters_initial\" style=\"display:none;\" value=\"1\">\n\n\t<div class=\"asl_option_inner hiddend\">\n\t\t<input type='hidden' name='qtranslate_lang' id='qtranslate_lang'\n\t\t\t\tvalue='0'\/>\n\t<\/div>\n\n\t\n\t\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Generic selectors<\/legend>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"exact\"\n\t\t\t\t\t\taria-label=\"Exact matches only\"\n\t\t\t\t\t\tname=\"asl_gen[]\" \/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tExact matches only\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"title\"\n\t\t\t\t\t\taria-label=\"Search in title\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in title\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"content\"\n\t\t\t\t\t\taria-label=\"Search in content\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in content\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t<input type=\"checkbox\" value=\"excerpt\"\n\t\t\t\t\taria-label=\"Search in excerpt\"\n\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t<\/div>\n\t<\/fieldset>\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Post Type Selectors<\/legend>\n\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"post\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"page\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t<\/fieldset>\n\t<\/form>\n\t<\/div>\n<\/div>\n<\/p>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-67d7f2a7cg\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27174\/\" class=\"_self\" target=\"_self\" >\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-31T13:45:23+07:00\">31\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/performance\/' title='\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19' class='pt-cv-tax-performance'>\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27104\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e08\u0e49\u0e07\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e04\u0e21\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-25T14:08:22+07:00\">25\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27101\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e04\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e04\u0e21\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-25T14:05:55+07:00\">25\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27088\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 4 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28.2569 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569 \u0e40\u0e27\u0e25\u0e32 09.30 \u0e19. \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e0a\u0e31\u0e49\u0e193 \u0e2d\u0e32\u0e04\u0e32\u0e23 One Stop Service \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-24T14:59:31+07:00\">24\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/affairs-council\/council-news\/' title='\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e2f' class='pt-cv-tax-council-news'>\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e2f<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26967\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e1e.\u0e28.2568 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-14T09:20:54+07:00\">14\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26888\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 4 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28.2569 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 11 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e40\u0e27\u0e25\u0e32 13.00 \u0e19. \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e0a\u0e31\u0e49\u0e19 3 \u0e2d\u0e32\u0e04\u0e32\u0e23 One Stop Service \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-10T09:28:00+07:00\">10\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/affairs-council\/council-news\/' title='\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e2f' class='pt-cv-tax-council-news'>\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e2f<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26861\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e48\u0e32\u0e27 \u0e2a\u0e04\u0e1a. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-22T00:03:30+07:00\">22\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26700\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e09\u0e25\u0e32\u0e01 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 23 (\u0e1e.\u0e28.2550) \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e0a\u0e38\u0e14\u0e2a\u0e31\u0e07\u0e06\u0e17\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e44\u0e17\u0e22\u0e18\u0e23\u0e23\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e09\u0e25\u0e32\u0e01<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-17T13:53:18+07:00\">17\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26747\/\" class=\"_self\" target=\"_self\" >\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2569<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-10T10:02:55+07:00\">10\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26612\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 4 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28.2569<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-08T16:20:37+07:00\">08\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/affairs-council\/council-news\/' title='\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e2f' class='pt-cv-tax-council-news'>\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e2f<\/a><\/span><\/div><\/div><\/div><\/div><\/div>\n<div class=\" pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"55\" data-currentpage=\"1\" data-sid=\"67d7f2a7cg\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=55\">55<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8456 alignnone\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR1.jpg\" alt=\"\" width=\"804\" height=\"67\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR1.jpg 804w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR1-660x55.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR1-768x64.jpg 768w\" sizes=\"auto, (max-width: 804px) 100vw, 804px\" \/><\/p>\n<p><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/\">\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a> &gt; <div class=\"asl_w_container asl_w_container_2\" data-id=\"2\" data-instance=\"1\">\n\t<div id='ajaxsearchlite2'\n\t\tdata-id=\"2\"\n\t\tdata-instance=\"1\"\n\t\tclass=\"asl_w asl_m asl_m_2 asl_m_2_1\">\n\t\t<div class=\"probox\">\n\n\t\n\t<div class='prosettings' style='display:none;' data-opened=0>\n\t\t\t\t<div class='innericon'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<polygon transform = \"rotate(90 256 256)\" points=\"142.332,104.886 197.48,50 402.5,256 197.48,462 142.332,407.113 292.727,256 \"\/>\n\t\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/div>\n\n\t\n\t\n\t<div class='proinput'>\n\t\t<form role=\"search\" action='#' autocomplete=\"off\"\n\t\t\t\taria-label=\"Search form\">\n\t\t\t<input aria-label=\"Search input\"\n\t\t\t\t\ttype='search' class='orig'\n\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tplaceholder='Search here..'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\"\/>\n\t\t\t<input aria-label=\"Search autocomplete input\"\n\t\t\t\t\ttype='text'\n\t\t\t\t\tclass='autocomplete'\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\" disabled\/>\n\t\t\t<input type='submit' value=\"Start search\" style='width:0; height: 0; visibility: hidden;'>\n\t\t<\/form>\n\t<\/div>\n\n\t\n\t\n\t<button class='promagnifier' tabindex=\"0\" aria-label=\"Search magnifier button\">\n\t\t\t\t<span class='innericon' style=\"display:block;\">\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<path d=\"M460.355,421.59L353.844,315.078c20.041-27.553,31.885-61.437,31.885-98.037\n\t\t\t\t\t\tC385.729,124.934,310.793,50,218.686,50C126.58,50,51.645,124.934,51.645,217.041c0,92.106,74.936,167.041,167.041,167.041\n\t\t\t\t\t\tc34.912,0,67.352-10.773,94.184-29.158L419.945,462L460.355,421.59z M100.631,217.041c0-65.096,52.959-118.056,118.055-118.056\n\t\t\t\t\t\tc65.098,0,118.057,52.959,118.057,118.056c0,65.096-52.959,118.056-118.057,118.056C153.59,335.097,100.631,282.137,100.631,217.041\n\t\t\t\t\t\tz\"\/>\n\t\t\t\t<\/svg>\n\t\t<\/span>\n\t<\/button>\n\n\t\n\t\n\t<div class='proloading'>\n\n\t\t<div class=\"asl_loader\"><div class=\"asl_loader-inner asl_simple-circle\"><\/div><\/div>\n\n\t\t\t<\/div>\n\n\t\t\t<div class='proclose'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\"\n\t\t\t\ty=\"0px\"\n\t\t\t\twidth=\"12\" height=\"12\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\"\n\t\t\t\txml:space=\"preserve\">\n\t\t\t\t<polygon points=\"438.393,374.595 319.757,255.977 438.378,137.348 374.595,73.607 255.995,192.225 137.375,73.622 73.607,137.352 192.246,255.983 73.622,374.625 137.352,438.393 256.002,319.734 374.652,438.378 \"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\n\t\n<\/div>\t<\/div>\n\t<div class='asl_data_container' style=\"display:none !important;\">\n\t\t<div class=\"asl_init_data wpdreams_asl_data_ct\"\n\tstyle=\"display:none !important;\"\n\tid=\"asl_init_id_2\"\n\tdata-asl-id=\"2\"\n\tdata-asl-instance=\"1\"\n\tdata-settings=\"{&quot;homeurl&quot;:&quot;https:\\\/\\\/www.tasaban-maemoh.go.th\\\/tbmm\\\/&quot;,&quot;resultstype&quot;:&quot;vertical&quot;,&quot;resultsposition&quot;:&quot;hover&quot;,&quot;itemscount&quot;:4,&quot;charcount&quot;:0,&quot;minWordLength&quot;:2,&quot;highlight&quot;:false,&quot;highlightWholewords&quot;:true,&quot;singleHighlight&quot;:false,&quot;scrollToResults&quot;:{&quot;enabled&quot;:false,&quot;offset&quot;:0},&quot;resultareaclickable&quot;:1,&quot;autocomplete&quot;:{&quot;enabled&quot;:true,&quot;lang&quot;:&quot;en&quot;,&quot;trigger_charcount&quot;:0},&quot;mobile&quot;:{&quot;menu_selector&quot;:&quot;#menu-toggle&quot;},&quot;trigger&quot;:{&quot;click&quot;:&quot;results_page&quot;,&quot;click_location&quot;:&quot;same&quot;,&quot;update_href&quot;:false,&quot;return&quot;:&quot;results_page&quot;,&quot;return_location&quot;:&quot;same&quot;,&quot;facet&quot;:true,&quot;type&quot;:true,&quot;redirect_url&quot;:&quot;?s={phrase}&quot;,&quot;delay&quot;:300},&quot;animations&quot;:{&quot;pc&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;},&quot;mob&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;}},&quot;autop&quot;:{&quot;state&quot;:true,&quot;phrase&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;},&quot;resPage&quot;:{&quot;useAjax&quot;:false,&quot;selector&quot;:&quot;#main&quot;,&quot;trigger_type&quot;:true,&quot;trigger_facet&quot;:true,&quot;trigger_magnifier&quot;:false,&quot;trigger_return&quot;:false},&quot;resultsSnapTo&quot;:&quot;left&quot;,&quot;results&quot;:{&quot;width&quot;:&quot;auto&quot;,&quot;width_tablet&quot;:&quot;auto&quot;,&quot;width_phone&quot;:&quot;auto&quot;},&quot;settingsimagepos&quot;:&quot;left&quot;,&quot;closeOnDocClick&quot;:true,&quot;overridewpdefault&quot;:false,&quot;override_method&quot;:&quot;get&quot;}\"><\/div>\n\t<\/div>\n\n\t<div id='ajaxsearchliteres2'\n\tclass='vertical wpdreams_asl_results asl_w asl_r asl_r_2 asl_r_2_1'>\n\n\t\n\t<div class=\"results\">\n\n\t\t\n\t\t<div class=\"resdrg\">\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n\t\n<\/div>\n\n\t<div id='__original__ajaxsearchlitesettings2'\n\t\tdata-id=\"2\"\n\t\tclass=\"searchsettings wpdreams_asl_settings asl_w asl_s asl_s_2\">\n\t\t<form name='options'\n\t\taria-label=\"Search settings form\"\n\t\tautocomplete = 'off'>\n\n\t\n\t\n\t<input type=\"hidden\" name=\"filters_changed\" style=\"display:none;\" value=\"0\">\n\t<input type=\"hidden\" name=\"filters_initial\" style=\"display:none;\" value=\"1\">\n\n\t<div class=\"asl_option_inner hiddend\">\n\t\t<input type='hidden' name='qtranslate_lang' id='qtranslate_lang'\n\t\t\t\tvalue='0'\/>\n\t<\/div>\n\n\t\n\t\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Generic selectors<\/legend>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"exact\"\n\t\t\t\t\t\taria-label=\"Exact matches only\"\n\t\t\t\t\t\tname=\"asl_gen[]\" \/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tExact matches only\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"title\"\n\t\t\t\t\t\taria-label=\"Search in title\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in title\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"content\"\n\t\t\t\t\t\taria-label=\"Search in content\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in content\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t<input type=\"checkbox\" value=\"excerpt\"\n\t\t\t\t\taria-label=\"Search in excerpt\"\n\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t<\/div>\n\t<\/fieldset>\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Post Type Selectors<\/legend>\n\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"post\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"page\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t<\/fieldset>\n\t<\/form>\n\t<\/div>\n<\/div>\n<\/p>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-a81f599tpn\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"3\"><div class=\"col-md-4 col-sm-2 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27137\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/08\/1-768x432.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<p class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27137\/\" class=\"_self\" target=\"_self\" >\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2569<\/a><\/p>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-27T10:57:01+07:00\">27\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/' title='\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21' class='pt-cv-tax-activity'>\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-4 col-sm-2 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27125\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/08\/\u0e1f\u0e49\u0e32-\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07-\u0e41\u0e25\u0e30\u0e41\u0e14\u0e07-\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32\u0e19-\u0e01\u0e35\u0e2c\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c-\u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e48\u0e32\u0e27-\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23-A4-768x1086.png\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<p class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27125\/\" class=\"_self\" target=\"_self\" >\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e1b\u0e34\u0e14\u0e09\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e0b\u0e1b\u0e31\u0e01\u0e15\u0e30\u0e01\u0e23\u0e49\u0e2d \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e32\u0e19\u0e20\u0e31\u0e22\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14<\/a><\/p>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-24T16:02:39+07:00\">24\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/' title='\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21' class='pt-cv-tax-activity'>\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-4 col-sm-2 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27128\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/08\/\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32-\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13-2569--768x1086.png\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<p class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27128\/\" class=\"_self\" target=\"_self\" >\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e01\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48<\/a><\/p>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-14T16:05:15+07:00\">14\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/' title='\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21' class='pt-cv-tax-activity'>\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-4 col-sm-2 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27014\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/08\/\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e21\u0e20\u0e1e-\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c-768x1086.png\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<p class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27014\/\" class=\"_self\" target=\"_self\" >\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e21\u0e20\u0e1e \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e41\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569<\/a><\/p>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-12T14:15:53+07:00\">12\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/' title='\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21' class='pt-cv-tax-activity'>\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-4 col-sm-2 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27005\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/08\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e484-768x1086.png\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<p class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27005\/\" class=\"_self\" target=\"_self\" >\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 4 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569<\/a><\/p>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-11T15:55:23+07:00\">11\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/' title='\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21' class='pt-cv-tax-activity'>\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-4 col-sm-2 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26820\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2026\/08\/\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e16\u0e27\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25-\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32-\u0e23-10.png\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<p class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26820\/\" class=\"_self\" target=\"_self\" >\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e16\u0e27\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e27\u0e0a\u0e34\u0e23\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27<\/a><\/p>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-28T10:54:31+07:00\">28\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/activity\/' title='\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21' class='pt-cv-tax-activity'>\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/a><\/span><\/div><\/div><\/div><\/div><\/div>\n<div class=\" pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"184\" data-currentpage=\"1\" data-sid=\"a81f599tpn\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=184\">184<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8461 alignnone\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR3.jpg\" alt=\"\" width=\"804\" height=\"67\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR3.jpg 804w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR3-660x55.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR3-768x64.jpg 768w\" sizes=\"auto, (max-width: 804px) 100vw, 804px\" \/><\/p>\n<p><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/\">\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a> &gt; <div class=\"asl_w_container asl_w_container_3\" data-id=\"3\" data-instance=\"1\">\n\t<div id='ajaxsearchlite3'\n\t\tdata-id=\"3\"\n\t\tdata-instance=\"1\"\n\t\tclass=\"asl_w asl_m asl_m_3 asl_m_3_1\">\n\t\t<div class=\"probox\">\n\n\t\n\t<div class='prosettings' style='display:none;' data-opened=0>\n\t\t\t\t<div class='innericon'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<polygon transform = \"rotate(90 256 256)\" points=\"142.332,104.886 197.48,50 402.5,256 197.48,462 142.332,407.113 292.727,256 \"\/>\n\t\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/div>\n\n\t\n\t\n\t<div class='proinput'>\n\t\t<form role=\"search\" action='#' autocomplete=\"off\"\n\t\t\t\taria-label=\"Search form\">\n\t\t\t<input aria-label=\"Search input\"\n\t\t\t\t\ttype='search' class='orig'\n\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tplaceholder='Search here..'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\"\/>\n\t\t\t<input aria-label=\"Search autocomplete input\"\n\t\t\t\t\ttype='text'\n\t\t\t\t\tclass='autocomplete'\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\" disabled\/>\n\t\t\t<input type='submit' value=\"Start search\" style='width:0; height: 0; visibility: hidden;'>\n\t\t<\/form>\n\t<\/div>\n\n\t\n\t\n\t<button class='promagnifier' tabindex=\"0\" aria-label=\"Search magnifier button\">\n\t\t\t\t<span class='innericon' style=\"display:block;\">\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<path d=\"M460.355,421.59L353.844,315.078c20.041-27.553,31.885-61.437,31.885-98.037\n\t\t\t\t\t\tC385.729,124.934,310.793,50,218.686,50C126.58,50,51.645,124.934,51.645,217.041c0,92.106,74.936,167.041,167.041,167.041\n\t\t\t\t\t\tc34.912,0,67.352-10.773,94.184-29.158L419.945,462L460.355,421.59z M100.631,217.041c0-65.096,52.959-118.056,118.055-118.056\n\t\t\t\t\t\tc65.098,0,118.057,52.959,118.057,118.056c0,65.096-52.959,118.056-118.057,118.056C153.59,335.097,100.631,282.137,100.631,217.041\n\t\t\t\t\t\tz\"\/>\n\t\t\t\t<\/svg>\n\t\t<\/span>\n\t<\/button>\n\n\t\n\t\n\t<div class='proloading'>\n\n\t\t<div class=\"asl_loader\"><div class=\"asl_loader-inner asl_simple-circle\"><\/div><\/div>\n\n\t\t\t<\/div>\n\n\t\t\t<div class='proclose'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\"\n\t\t\t\ty=\"0px\"\n\t\t\t\twidth=\"12\" height=\"12\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\"\n\t\t\t\txml:space=\"preserve\">\n\t\t\t\t<polygon points=\"438.393,374.595 319.757,255.977 438.378,137.348 374.595,73.607 255.995,192.225 137.375,73.622 73.607,137.352 192.246,255.983 73.622,374.625 137.352,438.393 256.002,319.734 374.652,438.378 \"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\n\t\n<\/div>\t<\/div>\n\t<div class='asl_data_container' style=\"display:none !important;\">\n\t\t<div class=\"asl_init_data wpdreams_asl_data_ct\"\n\tstyle=\"display:none !important;\"\n\tid=\"asl_init_id_3\"\n\tdata-asl-id=\"3\"\n\tdata-asl-instance=\"1\"\n\tdata-settings=\"{&quot;homeurl&quot;:&quot;https:\\\/\\\/www.tasaban-maemoh.go.th\\\/tbmm\\\/&quot;,&quot;resultstype&quot;:&quot;vertical&quot;,&quot;resultsposition&quot;:&quot;hover&quot;,&quot;itemscount&quot;:4,&quot;charcount&quot;:0,&quot;minWordLength&quot;:2,&quot;highlight&quot;:false,&quot;highlightWholewords&quot;:true,&quot;singleHighlight&quot;:false,&quot;scrollToResults&quot;:{&quot;enabled&quot;:false,&quot;offset&quot;:0},&quot;resultareaclickable&quot;:1,&quot;autocomplete&quot;:{&quot;enabled&quot;:true,&quot;lang&quot;:&quot;en&quot;,&quot;trigger_charcount&quot;:0},&quot;mobile&quot;:{&quot;menu_selector&quot;:&quot;#menu-toggle&quot;},&quot;trigger&quot;:{&quot;click&quot;:&quot;results_page&quot;,&quot;click_location&quot;:&quot;same&quot;,&quot;update_href&quot;:false,&quot;return&quot;:&quot;results_page&quot;,&quot;return_location&quot;:&quot;same&quot;,&quot;facet&quot;:true,&quot;type&quot;:true,&quot;redirect_url&quot;:&quot;?s={phrase}&quot;,&quot;delay&quot;:300},&quot;animations&quot;:{&quot;pc&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;},&quot;mob&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;}},&quot;autop&quot;:{&quot;state&quot;:true,&quot;phrase&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;},&quot;resPage&quot;:{&quot;useAjax&quot;:false,&quot;selector&quot;:&quot;#main&quot;,&quot;trigger_type&quot;:true,&quot;trigger_facet&quot;:true,&quot;trigger_magnifier&quot;:false,&quot;trigger_return&quot;:false},&quot;resultsSnapTo&quot;:&quot;left&quot;,&quot;results&quot;:{&quot;width&quot;:&quot;auto&quot;,&quot;width_tablet&quot;:&quot;auto&quot;,&quot;width_phone&quot;:&quot;auto&quot;},&quot;settingsimagepos&quot;:&quot;left&quot;,&quot;closeOnDocClick&quot;:true,&quot;overridewpdefault&quot;:false,&quot;override_method&quot;:&quot;get&quot;}\"><\/div>\n\t<\/div>\n\n\t<div id='ajaxsearchliteres3'\n\tclass='vertical wpdreams_asl_results asl_w asl_r asl_r_3 asl_r_3_1'>\n\n\t\n\t<div class=\"results\">\n\n\t\t\n\t\t<div class=\"resdrg\">\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n\t\n<\/div>\n\n\t<div id='__original__ajaxsearchlitesettings3'\n\t\tdata-id=\"3\"\n\t\tclass=\"searchsettings wpdreams_asl_settings asl_w asl_s asl_s_3\">\n\t\t<form name='options'\n\t\taria-label=\"Search settings form\"\n\t\tautocomplete = 'off'>\n\n\t\n\t\n\t<input type=\"hidden\" name=\"filters_changed\" style=\"display:none;\" value=\"0\">\n\t<input type=\"hidden\" name=\"filters_initial\" style=\"display:none;\" value=\"1\">\n\n\t<div class=\"asl_option_inner hiddend\">\n\t\t<input type='hidden' name='qtranslate_lang' id='qtranslate_lang'\n\t\t\t\tvalue='0'\/>\n\t<\/div>\n\n\t\n\t\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Generic selectors<\/legend>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"exact\"\n\t\t\t\t\t\taria-label=\"Exact matches only\"\n\t\t\t\t\t\tname=\"asl_gen[]\" \/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tExact matches only\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"title\"\n\t\t\t\t\t\taria-label=\"Search in title\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in title\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"content\"\n\t\t\t\t\t\taria-label=\"Search in content\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in content\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t<input type=\"checkbox\" value=\"excerpt\"\n\t\t\t\t\taria-label=\"Search in excerpt\"\n\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t<\/div>\n\t<\/fieldset>\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Post Type Selectors<\/legend>\n\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"post\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"page\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t<\/fieldset>\n\t<\/form>\n\t<\/div>\n<\/div>\n<\/p>\n<h2 style=\"text-align: right;\"><span style=\"color: #ff0000;\">\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 (<a style=\"color: #ff0000;\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/purchasing-results\/\">\u0e04\u0e25\u0e34\u0e01\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a<\/a>)<\/span><\/h2>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-20017b383e\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26902\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e41\u0e02\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32-\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e0a\u0e48\u0e27\u0e07\u0e25\u0e33\u0e2b\u0e49\u0e27\u0e22 \u0e16\u0e36\u0e07\u0e17\u0e32\u0e07\u0e41\u0e22\u0e01\u0e02\u0e49\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e41\u0e02\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48 11<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-10T15:26:55+07:00\">10\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26723\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01(\u0e14\u0e35\u0e40\u0e0b\u0e25) \u0e02\u0e19\u0e32\u0e14 1 \u0e15\u0e31\u0e19 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e15\u0e23\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01\u0e2a\u0e39\u0e1a\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 2,400 \u0e0b\u0e35\u0e0b\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 110 \u0e01\u0e34\u0e42\u0e25\u0e27\u0e31\u0e15\u0e15\u0e4c \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 2 \u0e25\u0e49\u0e2d \u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e41\u0e04\u0e47\u0e1a \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-21T15:14:38+07:00\">21\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26442\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 (\u0e14\u0e35\u0e40\u0e0b\u0e25) \u0e02\u0e19\u0e32\u0e14 1 \u0e15\u0e31\u0e19 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e15\u0e23\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01\u0e2a\u0e39\u0e1a\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 2,400 \u0e0b\u0e35\u0e0b\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 110 \u0e01\u0e34\u0e42\u0e25\u0e27\u0e31\u0e15\u0e15\u0e4c \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 4 \u0e25\u0e49\u0e2d \u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e41\u0e04\u0e47\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-30T09:18:31+07:00\">30\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26439\/\" class=\"_self\" target=\"_self\" >\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e16\u0e19\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e44\u0e2b\u0e25\u0e48\u0e16\u0e19\u0e19 \u0e04.\u0e2a.\u0e25. \u0e2a\u0e32\u0e22\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e32\u0e30\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48 8<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-30T09:15:38+07:00\">30\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26430\/\" class=\"_self\" target=\"_self\" >\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e1f\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e17\u0e32\u0e07\u0e23\u0e48\u0e27\u0e21 \u0e17\u0e32\u0e07\u0e41\u0e22\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e32\u0e30\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48 8<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-29T13:52:39+07:00\">29\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26427\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e22\u0e40\u0e02\u0e49\u0e32\u0e27\u0e31\u0e14\u0e23\u0e31\u0e15\u0e19\u0e04\u0e39\u0e2b\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07\u0e2b\u0e07\u0e2a\u0e4c\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e4812<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-29T13:46:42+07:00\">29\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26411\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e0b\u0e2d\u0e22 6 \u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e19\u0e32\u0e41\u0e02\u0e21 \u0e2b\u0e21\u0e39\u0e48 7<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-26T10:37:32+07:00\">26\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26362\/\" class=\"_self\" target=\"_self\" >(\u0e23\u0e48\u0e32\u0e07) \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 (\u0e14\u0e35\u0e40\u0e0b\u0e25) \u0e02\u0e19\u0e32\u0e14 1 \u0e15\u0e31\u0e19 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e15\u0e23\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01\u0e2a\u0e39\u0e1a\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 2,400 \u0e0b\u0e35\u0e0b\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 110 \u0e01\u0e34\u0e42\u0e25\u0e27\u0e31\u0e15\u0e15\u0e4c \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 4 \u0e25\u0e49\u0e2d \u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e41\u0e04\u0e47\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-23T15:51:42+07:00\">23\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26201\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-11T14:31:21+07:00\">11\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h5 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26198\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07 (\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e02\u0e22\u0e30 \u0e02\u0e19\u0e32\u0e14 6 \u0e15\u0e31\u0e19 6 \u0e25\u0e49\u0e2d \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e15\u0e23\u0e01\u0e23\u0e30\u0e1a\u0e2d\u0e01\u0e2a\u0e39\u0e1a\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 6000 \u0e0b\u0e35\u0e0b\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 170 \u0e01\u0e34\u0e42\u0e25\u0e27\u0e31\u0e15\u0e15\u0e4c \u0e41\u0e1a\u0e1a\u0e2d\u0e31\u0e14\u0e17\u0e49\u0e32\u0e22) \u0e15\u0e32\u0e21\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h5>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-06-11T14:29:06+07:00\">11\/06\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/purchase\/purchase1\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07' class='pt-cv-tax-purchase1'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07<\/a><\/span><\/div><\/div><\/div><\/div><\/div>\n<div class=\" pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"33\" data-currentpage=\"1\" data-sid=\"20017b383e\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=33\">33<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8463 alignnone\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR4.jpg\" alt=\"\" width=\"804\" height=\"67\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR4.jpg 804w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR4-660x55.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/Bar-PR4-768x64.jpg 768w\" sizes=\"auto, (max-width: 804px) 100vw, 804px\" \/><\/p>\n<p><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/\">\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e02\u0e48\u0e32\u0e27\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a> &gt; <div class=\"asl_w_container asl_w_container_4\" data-id=\"4\" data-instance=\"1\">\n\t<div id='ajaxsearchlite4'\n\t\tdata-id=\"4\"\n\t\tdata-instance=\"1\"\n\t\tclass=\"asl_w asl_m asl_m_4 asl_m_4_1\">\n\t\t<div class=\"probox\">\n\n\t\n\t<div class='prosettings' style='display:none;' data-opened=0>\n\t\t\t\t<div class='innericon'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<polygon transform = \"rotate(90 256 256)\" points=\"142.332,104.886 197.48,50 402.5,256 197.48,462 142.332,407.113 292.727,256 \"\/>\n\t\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/div>\n\n\t\n\t\n\t<div class='proinput'>\n\t\t<form role=\"search\" action='#' autocomplete=\"off\"\n\t\t\t\taria-label=\"Search form\">\n\t\t\t<input aria-label=\"Search input\"\n\t\t\t\t\ttype='search' class='orig'\n\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tplaceholder='Search here..'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\"\/>\n\t\t\t<input aria-label=\"Search autocomplete input\"\n\t\t\t\t\ttype='text'\n\t\t\t\t\tclass='autocomplete'\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t\tname='phrase'\n\t\t\t\t\tvalue=''\n\t\t\t\t\tautocomplete=\"off\" disabled\/>\n\t\t\t<input type='submit' value=\"Start search\" style='width:0; height: 0; visibility: hidden;'>\n\t\t<\/form>\n\t<\/div>\n\n\t\n\t\n\t<button class='promagnifier' tabindex=\"0\" aria-label=\"Search magnifier button\">\n\t\t\t\t<span class='innericon' style=\"display:block;\">\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"22\" height=\"22\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t\t<path d=\"M460.355,421.59L353.844,315.078c20.041-27.553,31.885-61.437,31.885-98.037\n\t\t\t\t\t\tC385.729,124.934,310.793,50,218.686,50C126.58,50,51.645,124.934,51.645,217.041c0,92.106,74.936,167.041,167.041,167.041\n\t\t\t\t\t\tc34.912,0,67.352-10.773,94.184-29.158L419.945,462L460.355,421.59z M100.631,217.041c0-65.096,52.959-118.056,118.055-118.056\n\t\t\t\t\t\tc65.098,0,118.057,52.959,118.057,118.056c0,65.096-52.959,118.056-118.057,118.056C153.59,335.097,100.631,282.137,100.631,217.041\n\t\t\t\t\t\tz\"\/>\n\t\t\t\t<\/svg>\n\t\t<\/span>\n\t<\/button>\n\n\t\n\t\n\t<div class='proloading'>\n\n\t\t<div class=\"asl_loader\"><div class=\"asl_loader-inner asl_simple-circle\"><\/div><\/div>\n\n\t\t\t<\/div>\n\n\t\t\t<div class='proclose'>\n\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\"\n\t\t\t\ty=\"0px\"\n\t\t\t\twidth=\"12\" height=\"12\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\"\n\t\t\t\txml:space=\"preserve\">\n\t\t\t\t<polygon points=\"438.393,374.595 319.757,255.977 438.378,137.348 374.595,73.607 255.995,192.225 137.375,73.622 73.607,137.352 192.246,255.983 73.622,374.625 137.352,438.393 256.002,319.734 374.652,438.378 \"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\n\t\n<\/div>\t<\/div>\n\t<div class='asl_data_container' style=\"display:none !important;\">\n\t\t<div class=\"asl_init_data wpdreams_asl_data_ct\"\n\tstyle=\"display:none !important;\"\n\tid=\"asl_init_id_4\"\n\tdata-asl-id=\"4\"\n\tdata-asl-instance=\"1\"\n\tdata-settings=\"{&quot;homeurl&quot;:&quot;https:\\\/\\\/www.tasaban-maemoh.go.th\\\/tbmm\\\/&quot;,&quot;resultstype&quot;:&quot;vertical&quot;,&quot;resultsposition&quot;:&quot;hover&quot;,&quot;itemscount&quot;:4,&quot;charcount&quot;:0,&quot;minWordLength&quot;:2,&quot;highlight&quot;:false,&quot;highlightWholewords&quot;:true,&quot;singleHighlight&quot;:false,&quot;scrollToResults&quot;:{&quot;enabled&quot;:false,&quot;offset&quot;:0},&quot;resultareaclickable&quot;:1,&quot;autocomplete&quot;:{&quot;enabled&quot;:true,&quot;lang&quot;:&quot;en&quot;,&quot;trigger_charcount&quot;:0},&quot;mobile&quot;:{&quot;menu_selector&quot;:&quot;#menu-toggle&quot;},&quot;trigger&quot;:{&quot;click&quot;:&quot;results_page&quot;,&quot;click_location&quot;:&quot;same&quot;,&quot;update_href&quot;:false,&quot;return&quot;:&quot;results_page&quot;,&quot;return_location&quot;:&quot;same&quot;,&quot;facet&quot;:true,&quot;type&quot;:true,&quot;redirect_url&quot;:&quot;?s={phrase}&quot;,&quot;delay&quot;:300},&quot;animations&quot;:{&quot;pc&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;},&quot;mob&quot;:{&quot;settings&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;results&quot;:{&quot;anim&quot;:&quot;fadedrop&quot;,&quot;dur&quot;:300},&quot;items&quot;:&quot;voidanim&quot;}},&quot;autop&quot;:{&quot;state&quot;:true,&quot;phrase&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;},&quot;resPage&quot;:{&quot;useAjax&quot;:false,&quot;selector&quot;:&quot;#main&quot;,&quot;trigger_type&quot;:true,&quot;trigger_facet&quot;:true,&quot;trigger_magnifier&quot;:false,&quot;trigger_return&quot;:false},&quot;resultsSnapTo&quot;:&quot;left&quot;,&quot;results&quot;:{&quot;width&quot;:&quot;auto&quot;,&quot;width_tablet&quot;:&quot;auto&quot;,&quot;width_phone&quot;:&quot;auto&quot;},&quot;settingsimagepos&quot;:&quot;left&quot;,&quot;closeOnDocClick&quot;:true,&quot;overridewpdefault&quot;:false,&quot;override_method&quot;:&quot;get&quot;}\"><\/div>\n\t<\/div>\n\n\t<div id='ajaxsearchliteres4'\n\tclass='vertical wpdreams_asl_results asl_w asl_r asl_r_4 asl_r_4_1'>\n\n\t\n\t<div class=\"results\">\n\n\t\t\n\t\t<div class=\"resdrg\">\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n\t\n<\/div>\n\n\t<div id='__original__ajaxsearchlitesettings4'\n\t\tdata-id=\"4\"\n\t\tclass=\"searchsettings wpdreams_asl_settings asl_w asl_s asl_s_4\">\n\t\t<form name='options'\n\t\taria-label=\"Search settings form\"\n\t\tautocomplete = 'off'>\n\n\t\n\t\n\t<input type=\"hidden\" name=\"filters_changed\" style=\"display:none;\" value=\"0\">\n\t<input type=\"hidden\" name=\"filters_initial\" style=\"display:none;\" value=\"1\">\n\n\t<div class=\"asl_option_inner hiddend\">\n\t\t<input type='hidden' name='qtranslate_lang' id='qtranslate_lang'\n\t\t\t\tvalue='0'\/>\n\t<\/div>\n\n\t\n\t\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Generic selectors<\/legend>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"exact\"\n\t\t\t\t\t\taria-label=\"Exact matches only\"\n\t\t\t\t\t\tname=\"asl_gen[]\" \/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tExact matches only\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"title\"\n\t\t\t\t\t\taria-label=\"Search in title\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in title\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option\" tabindex=\"0\">\n\t\t\t<div class=\"asl_option_inner\">\n\t\t\t\t<input type=\"checkbox\" value=\"content\"\n\t\t\t\t\t\taria-label=\"Search in content\"\n\t\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"asl_option_label\">\n\t\t\t\tSearch in content\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t<input type=\"checkbox\" value=\"excerpt\"\n\t\t\t\t\taria-label=\"Search in excerpt\"\n\t\t\t\t\tname=\"asl_gen[]\"  checked=\"checked\"\/>\n\t\t\t<div class=\"asl_option_checkbox\"><\/div>\n\t\t<\/div>\n\t<\/fieldset>\n\t<fieldset class=\"asl_sett_scroll\">\n\t\t<legend style=\"display: none;\">Post Type Selectors<\/legend>\n\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"post\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"asl_option_inner hiddend\">\n\t\t\t\t<input type=\"checkbox\" value=\"page\"\n\t\t\t\t\t\taria-label=\"Hidden option, ignore please\"\n\t\t\t\t\t\tname=\"customset[]\" checked=\"checked\"\/>\n\t\t\t<\/div>\n\t\t\t\t<\/fieldset>\n\t<\/form>\n\t<\/div>\n<\/div>\n<\/p>\n\t\t\t\t\t\t<style>\r\n\t\t\t\t\r\n\t\t\t\t\t#tab_container_21970 {\r\n\toverflow:hidden;\r\n\tdisplay:block;\r\n\twidth:100%;\r\n\tborder:0px solid #ddd;\r\n\tmargin-bottom:30px;\r\n\t}\r\n\r\n#tab_container_21970 .tab-content{\r\n\tpadding:20px;\r\n\tborder: 1px solid #e6e6e6 !important;\r\n\tmargin-top: 0px;\r\n\tbackground-color:#ffffff !important;\r\n\tcolor: #000000 !important;\r\n\tfont-size:16px !important;\r\n\tfont-family: Open Sans !important;\r\n\t\r\n\t\tborder: 1px solid #e6e6e6 !important;\r\n\t}\r\n#tab_container_21970 .wpsm_nav-tabs {\r\n    border-bottom: 0px solid #ddd;\r\n}\r\n#tab_container_21970 .wpsm_nav-tabs > li.active > a, #tab_container_21970 .wpsm_nav-tabs > li.active > a:hover, #tab_container_21970 .wpsm_nav-tabs > li.active > a:focus {\r\n\tcolor: #000000 !important;\r\n\tcursor: default;\r\n\tbackground-color: #ffffff !important;\r\n\tborder: 1px solid #e6e6e6 !important;\r\n}\r\n\r\n#tab_container_21970 .wpsm_nav-tabs > li > a {\r\n    margin-right: 0px !important; \r\n    line-height: 1.42857143 !important;\r\n    border: 1px solid #d5d5d5 !important;\r\n    border-radius: 0px 0px 0 0 !important; \r\n\tbackground-color: #e8e8e8 !important;\r\n\tcolor: #000000 !important;\r\n\tpadding: 15px 18px 15px 18px !important;\r\n\ttext-decoration: none !important;\r\n\tfont-size: 14px !important;\r\n\ttext-align:center !important;\r\n\tfont-family: Open Sans !important;\r\n}\r\n#tab_container_21970 .wpsm_nav-tabs > li > a:focus {\r\noutline: 0px !important;\r\n}\r\n\r\n#tab_container_21970 .wpsm_nav-tabs > li > a:before {\r\n\tdisplay:none !important;\r\n}\r\n#tab_container_21970 .wpsm_nav-tabs > li > a:after {\r\n\tdisplay:none !important ;\r\n}\r\n#tab_container_21970 .wpsm_nav-tabs > li{\r\npadding:0px !important ;\r\nmargin:0px;\r\n}\r\n\r\n#tab_container_21970 .wpsm_nav-tabs > li > a:hover , #tab_container_21970 .wpsm_nav-tabs > li > a:focus {\r\n    color: #000000 !important;\r\n    background-color: #e8e8e8 !important;\r\n\tborder: 1px solid #d5d5d5 !important;\r\n\t\r\n}\r\n#tab_container_21970 .wpsm_nav-tabs > li > a .fa{\r\n\r\nmargin-right:5px !important;\r\n\r\nmargin-left:5px !important;\r\n\r\n\r\n}\r\n\r\n\t\t#tab_container_21970 .wpsm_nav-tabs a{\r\n\t\t\tbackground-image: none;\r\n\t\t\tbackground-position: 0 0;\r\n\t\t\tbackground-repeat: repeat-x;\r\n\t\t}\r\n\t\t\t\r\n\r\n\r\n#tab_container_21970 .wpsm_nav-tabs > li {\r\n    float: left;\r\n    margin-bottom: -1px !important;\r\n\tmargin-right:0px !important; \r\n}\r\n\r\n\r\n#tab_container_21970 .tab-content{\r\noverflow:hidden !important;\r\n}\r\n\r\n\r\n@media (min-width: 769px) {\r\n\r\n\t#tab_container_21970 .wpsm_nav-tabs > li{\r\n\t\tfloat:left !important ;\r\n\t\t\t\tmargin-right:-1px !important;\r\n\t\t\t\t\t}\r\n\t#tab_container_21970 .wpsm_nav-tabs{\r\n\t\tfloat:none !important;\r\n\t\tmargin:0px !important;\r\n\t}\r\n\r\n\t#tab_container_21970 .wpsm_nav-tabs > li {\r\n\t\t\t\t\r\n\t}\r\n\t#tab_container_21970 .wpsm_nav{\r\n\t\t\t}\r\n\r\n}\r\n\r\n\r\n\r\n@media (max-width: 768px) {\r\n\t#tab_container_21970 .wpsm_nav-tabs > li {\r\n\t\t\t\t\r\n\t}\r\n\t#tab_container_21970 .wpsm_nav{\r\n\t\t\t}\r\n}\r\n\r\n\r\n\t.wpsm_nav-tabs li:before{\r\n\t\tdisplay:none !important;\r\n\t}\r\n\r\n\t@media (max-width: 768px) {\r\n\t\t\t\t\r\n\t\t\t\t.wpsm_nav-tabs{\r\n\t\t\tmargin-left:0px !important;\r\n\t\t\tmargin-right:0px !important; \r\n\t\t\t\r\n\t\t}\r\n\t\t\t\t#tab_container_21970 .wpsm_nav-tabs > li{\r\n\t\t\tfloat:none !important;\r\n\t\t}\r\n\t\t\t\r\n\t}\t\t\t\t<\/style>\r\n\t\t\t\t<div id=\"tab_container_21970\" >\r\n\t \r\n\t\t\t\t\t<ul class=\"wpsm_nav wpsm_nav-tabs\" role=\"tablist\" id=\"myTab_21970\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<li role=\"presentation\"  class=\"active\"  onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t<a href=\"#tabs_desc_21970_1\" aria-controls=\"tabs_desc_21970_1\" role=\"tab\" data-toggle=\"tab\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-bullhorn\"><\/i> \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<span>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/span>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<li role=\"presentation\"  onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t<a href=\"#tabs_desc_21970_2\" aria-controls=\"tabs_desc_21970_2\" role=\"tab\" data-toggle=\"tab\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-bullhorn\"><\/i> \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<span>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22<\/span>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<li role=\"presentation\"  onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t<a href=\"#tabs_desc_21970_3\" aria-controls=\"tabs_desc_21970_3\" role=\"tab\" data-toggle=\"tab\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-edit\"><\/i> \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<span>Coming soon...<\/span>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t <\/ul>\r\n\r\n\t\t\t\t\t  <!-- Tab panes -->\r\n\t\t\t\t\t  <div class=\"tab-content\" id=\"tab-content_21970\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t <div role=\"tabpanel\" class=\"tab-pane  in active \" id=\"tabs_desc_21970_1\">\r\n\t\t\t\t\t\t\t\t<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-5137b9cz29\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27181\/\" class=\"_blank\" target=\"_blank\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2a\u0e2d\u0e1a \u0e27\u0e31\u0e19 \u0e40\u0e27\u0e25\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a \u0e02\u0e49\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e2d\u0e1a \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e1e.\u0e28.2569<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-08-31T16:07:20+07:00\">31\/08\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/job-announcement\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19' class='pt-cv-tax-job-announcement'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/26704\/\" class=\"_blank\" target=\"_blank\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e1e.\u0e28.2569 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e19\u0e32\u0e22\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32, \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19 3 \u0e2d\u0e31\u0e15\u0e23\u0e32 \u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e37\u0e48\u0e19\u0e43\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569 \u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-07-17T15:37:05+07:00\">17\/07\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/job-announcement\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19' class='pt-cv-tax-job-announcement'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/23812\/\" class=\"_blank\" target=\"_blank\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e44\u0e14\u0e49 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07\u0e15\u0e32\u0e21\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e19\u0e32\u0e22\u0e0a\u0e48\u0e32\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07\u0e15\u0e32\u0e21\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e23\u0e16\u0e02\u0e22\u0e30 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e1e.\u0e28.2568 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2025-12-23T15:56:22+07:00\">23\/12\/2025<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/job-announcement\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19' class='pt-cv-tax-job-announcement'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/23625\/\" class=\"_blank\" target=\"_blank\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e04\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 (\u0e20\u0e32\u0e04 \u0e04) \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e04\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 (\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c) \u0e27\u0e31\u0e19 \u0e40\u0e27\u0e25\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e2d\u0e1a \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e1e.\u0e28.2568<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2025-12-03T14:47:50+07:00\">03\/12\/2025<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/job-announcement\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19' class='pt-cv-tax-job-announcement'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/23470\/\" class=\"_blank\" target=\"_blank\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e02\u0e36\u0e49\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e44\u0e14\u0e49 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e19\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e23\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e1e.\u0e28.2568<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2025-11-20T12:42:28+07:00\">20\/11\/2025<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/job-announcement\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19' class='pt-cv-tax-job-announcement'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19<\/a><\/span><\/div><\/div><\/div><\/div><\/div>\n<div class=\" pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"11\" data-currentpage=\"1\" data-sid=\"5137b9cz29\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=11\">11<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\t\t\t\t\t\t <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t <div role=\"tabpanel\" class=\"tab-pane \" id=\"tabs_desc_21970_2\">\r\n\t\t\t\t\t\t\t\t<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-1fd723egji\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/25311\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 (\u0e22\u0e49\u0e32\u0e22) \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e23\u0e39\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e23\u0e39\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e23\u0e39 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e07 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e2d\u0e01\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-05-07T12:33:32+07:00\">07\/05\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/announcement-of-transfer\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22' class='pt-cv-tax-announcement-of-transfer'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/25072\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e07 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e19\u0e32\u0e22\u0e0a\u0e48\u0e32\u0e07\u0e42\u0e22\u0e18\u0e32 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-04-20T10:00:32+07:00\">20\/04\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/announcement-of-transfer\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22' class='pt-cv-tax-announcement-of-transfer'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/24682\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 (\u0e22\u0e49\u0e32\u0e22) \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e23\u0e39\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e23\u0e39\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e23\u0e39 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e07 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e04\u0e23\u0e39 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e2d\u0e31\u0e15\u0e23\u0e32 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-03-17T09:24:44+07:00\">17\/03\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/prnews\/' title='\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c' class='pt-cv-tax-prnews'>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/a>, <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/announcement-of-transfer\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22' class='pt-cv-tax-announcement-of-transfer'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/24316\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e07 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2026-02-16T08:35:29+07:00\">16\/02\/2026<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/announcement-of-transfer\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22' class='pt-cv-tax-announcement-of-transfer'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22<\/a><\/span><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/22389\/\" class=\"_self\" target=\"_self\" >\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e30\u0e27\u0e48\u0e32\u0e07 \u0e01\u0e23\u0e13\u0e35\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e2d\u0e32\u0e22\u0e38\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a<\/a><\/h4>\n<div class=\"pt-cv-meta-fields\"><span class=\"entry-date\"> <time datetime=\"2025-08-04T10:50:16+07:00\">04\/08\/2025<\/time><\/span><span> \/ <\/span><span class=\"terms\"> <a href='https:\/\/www.tasaban-maemoh.go.th\/tbmm\/category\/jobnews\/announcement-of-transfer\/' title='\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22' class='pt-cv-tax-announcement-of-transfer'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22<\/a><\/span><\/div><\/div><\/div><\/div><\/div>\n<div class=\" pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"8\" data-currentpage=\"1\" data-sid=\"1fd723egji\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=8\">8<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\t\t\t\t\t\t <\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t <div role=\"tabpanel\" class=\"tab-pane \" id=\"tabs_desc_21970_3\">\r\n\t\t\t\t\t\t\t\tComing soon...\t\t\t\t\t\t <\/div>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t <\/div>\r\n\t\t\t\t\t \r\n\t\t\t\t <\/div>\r\n <script>\r\n\t\tjQuery(function () {\r\n\t\t\tjQuery('#myTab_21970 a:first').tab('show')\r\n\t\t});\r\n\t\t\r\n\t\t\t\tjQuery(function(){\r\n\t\t\tvar b=\"fadeIn\";\r\n\t\t\tvar c;\r\n\t\t\tvar a;\r\n\t\t\td(jQuery(\"#myTab_21970 a\"),jQuery(\"#tab-content_21970\"));function d(e,f,g){\r\n\t\t\t\te.click(function(i){\r\n\t\t\t\t\ti.preventDefault();\r\n\t\t\t\t\tjQuery(this).tab(\"show\");\r\n\t\t\t\t\tvar h=jQuery(this).data(\"easein\");\r\n\t\t\t\t\tif(c){c.removeClass(a);}\r\n\t\t\t\t\tif(h){f.find(\"div.active\").addClass(\"animated \"+h);a=h;}\r\n\t\t\t\t\telse{if(g){f.find(\"div.active\").addClass(\"animated \"+g);a=g;}else{f.find(\"div.active\").addClass(\"animated \"+b);a=b;}}c=f.find(\"div.active\");\r\n\t\t\t\t});\r\n\t\t\t}\r\n\t\t});\r\n\t\t\r\n\r\n\t\tfunction do_resize(){\r\n\r\n\t\t\tvar width=jQuery( '.tab-content .tab-pane iframe' ).width();\r\n\t\t\tvar height=jQuery( '.tab-content .tab-pane iframe' ).height();\r\n\r\n\t\t\tvar toggleSize = true;\r\n\t\t\tjQuery('iframe').animate({\r\n\t\t\t    width: toggleSize ? width : 640,\r\n\t\t\t    height: toggleSize ? height : 360\r\n\t\t\t  }, 250);\r\n\r\n\t\t\t  toggleSize = !toggleSize;\r\n\t\t}\r\n\r\n\r\n\t<\/script>\r\n\t\t\t\t\r\n\t\t\t\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-23854 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/12\/PR-\u0e20\u0e32\u0e29\u0e35.jpg\" alt=\"\" width=\"2048\" height=\"1024\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/12\/PR-\u0e20\u0e32\u0e29\u0e35.jpg 2048w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/12\/PR-\u0e20\u0e32\u0e29\u0e35-660x330.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/12\/PR-\u0e20\u0e32\u0e29\u0e35-840x420.jpg 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/12\/PR-\u0e20\u0e32\u0e29\u0e35-768x384.jpg 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2025\/12\/PR-\u0e20\u0e32\u0e29\u0e35-1536x768.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n\n<p><a style=\"background-color: #ffffff;\" href=\"http:\/\/www.tasaban-maemoh.go.th\/radio\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5493 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio.jpg\" alt=\"\" width=\"2263\" height=\"812\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio.jpg 2263w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio-660x237.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio-768x276.jpg 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio-840x301.jpg 840w\" sizes=\"auto, (max-width: 2263px) 100vw, 2263px\" \/><\/a><\/p>\n<div class=\"pjnt-border\" style=\"font-family: nvalid URL, sans-serif; background-color: #1e73be; border-color: #1e73be;\"><div class=\"pjnt-label\" style=\"color: #ffffff; font-size: 100%;\">Latest Posts<\/div><div class=\"pjnt-box\" style=\"background-color: #ffffff;\"><div class=\"pjnt-content\" data-gap=\"true\" data-speed=\"40\" style=\"font-size: 100%;\"><span class=\"pjnt-item\"><a target=\"_self\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27137\/\">\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2569<\/a><\/span><span class=\"pjnt-item\"><a target=\"_self\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27125\/\">\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e1b\u0e34\u0e14\u0e09\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e0b\u0e1b\u0e31\u0e01\u0e15\u0e30\u0e01\u0e23\u0e49\u0e2d \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e32\u0e19\u0e20\u0e31\u0e22\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14<\/a><\/span><span class=\"pjnt-item\"><a target=\"_self\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27128\/\">\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e01\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48<\/a><\/span><span class=\"pjnt-item\"><a target=\"_self\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27014\/\">\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e21\u0e20\u0e1e \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e41\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569<\/a><\/span><span class=\"pjnt-item\"><a target=\"_self\" href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/27005\/\">\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e20\u0e32\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 4 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569<\/a><\/span><\/div><\/div><\/div>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #ffffff;\" href=\"http:\/\/www.tasaban-maemoh.go.th\/mmcc\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7351 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/1600x400.jpg\" alt=\"\" width=\"1600\" height=\"400\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/1600x400.jpg 1600w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/1600x400-660x165.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/1600x400-768x192.jpg 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/1600x400-840x210.jpg 840w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p><a style=\"background-color: #ffffff;\" href=\"https:\/\/www.prmaemoh.com\/tour\/tourist-information-center\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17728 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/06\/Tour.jpg\" alt=\"\" width=\"1200\" height=\"320\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/06\/Tour.jpg 1200w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/06\/Tour-660x176.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/06\/Tour-840x224.jpg 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/06\/Tour-768x205.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16198 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2023\/09\/313432138_3804150596507562_4159354820083457191_n.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2023\/09\/313432138_3804150596507562_4159354820083457191_n.jpg 1200w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2023\/09\/313432138_3804150596507562_4159354820083457191_n-548x365.jpg 548w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2023\/09\/313432138_3804150596507562_4159354820083457191_n-840x560.jpg 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2023\/09\/313432138_3804150596507562_4159354820083457191_n-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n\n\n<div id=\"sb_youtube_sbyUC0aF21CLYcEVv6G3KKfw12\" \n\t class=\"sb_youtube sby_layout_grid sby_col_3 sby_mob_col_2 sby_palette_inherit  sby_width_resp\" \n\tdata-feedid=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw#12\" \n\tdata-shortcode-atts=\"{}\" \n\tdata-cols=\"3\" \n\tdata-colsmobile=\"2\" \n\tdata-num=\"12\" \n\tdata-nummobile=\"9\" \n\tdata-channel-subscribers=\"&lt;span class=&quot;sby_loader&quot; style=&quot;background-color: rgb(255, 255, 255);&quot;&gt;&lt;\/span&gt; subscribers\"\tdata-subscribe-btn=\"1\" \n\tdata-subscribe-btn-text=\"Subscribe\" \n\tdata_channel_header_colors =\"{&quot;channelName&quot;:&quot;&quot;,&quot;subscribeCount&quot;:&quot;&quot;,&quot;buttonBackground&quot;:&quot;&quot;,&quot;buttonText&quot;:&quot;&quot;}\"\n\t data-sby-flags=\"checkWPPosts,resizeDisable\" data-postid=\"12403\" data-sby-supports-lightbox=\"1\" style=\"width: 100%;\" \n\t data-videocardlayout=\"vertical\" \n>\n\t<div class=\"sb_youtube_header \" >\n    <a href=\"https:\/\/www.youtube.com\/channel\/UC-0aF2-1CLYcEVv6G3K_Kfw\/\" target=\"_blank\" rel=\"noopener\" title=\"@\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e4d\u0e32\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\" class=\"sby_header_link\" data-channel-description=\"visible\">\n        <div class=\"sby_header_text sby_no_bio sby_no_sub\"  data-header-subscriber=\"shown\">\n            <h3 >\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e4d\u0e32\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30<\/h3>\n\t\t\t        <\/div>\n        <div class=\"sby_header_img\" data-avatar-url=\"https:\/\/yt3.ggpht.com\/a\/AATXAJyvhEr5czykKG25wsNOEMBgCXhy0wHWMSJbTg=s88-c-k-c0xffffffff-no-rj-mo\">\n            <div class=\"sby_header_img_hover\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"sby_new_logo svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg><\/div>\n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/yt3.ggpht.com\/a\/AATXAJyvhEr5czykKG25wsNOEMBgCXhy0wHWMSJbTg=s88-c-k-c0xffffffff-no-rj-mo\" alt=\"\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e4d\u0e32\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\" width=\"50\" height=\"50\">\n        <\/div>\n    <\/a>\n<\/div>        <div class=\"sby_items_wrap\" style=\"padding: 5px;\">\n\t\t<div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_awcNdaFbaak\" data-date=\"1781501668\" data-video-id=\"awcNdaFbaak\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=awcNdaFbaak\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i2.ytimg.com\/vi\/awcNdaFbaak\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/awcNdaFbaak\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/awcNdaFbaak\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/awcNdaFbaak\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/awcNdaFbaak\\\/sddefault.jpg&quot;}\" data-video-id=\"awcNdaFbaak\" data-video-title=\"\u0e27\u0e34\u0e14\u0e35\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e14\u0e39\u0e07\u0e32\u0e19 (\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14)1\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_gzWJXbY5jOk\" data-date=\"1776897130\" data-video-id=\"gzWJXbY5jOk\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=gzWJXbY5jOk\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i4.ytimg.com\/vi\/gzWJXbY5jOk\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/gzWJXbY5jOk\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/gzWJXbY5jOk\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/gzWJXbY5jOk\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/gzWJXbY5jOk\\\/sddefault.jpg&quot;}\" data-video-id=\"gzWJXbY5jOk\" data-video-title=\"\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e23\u0e2d\u0e1a\u0e23\u0e31\u0e49\u0e27\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2f\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83d\udcdf\u0e0a\u0e27\u0e19\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \ud83d\udcfc \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e23\u0e2d\u0e1a\u0e23\u0e31\u0e49\u0e27\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2f \n\ud83d\udd34\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e0a\u0e21\n- \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c http:\/\/www.tasaban-maemoh.go.th\/radio\n- \u0e40\u0e1e\u0e08 Facebook : \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \n- \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n\ud83d\udd34\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\n- \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e27\u0e34\u0e17\u0e22\u0e38 R-Radio Network FM 99.50 MHz \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e1f\u0e1c.\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n\u23f1\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23 10.00 - 12.00 \u0e19.\n\u23f1\u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c 13.00 - 15.00 \u0e19.\n\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22 : \u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e08\u0e31\u0e01\u0e1a\u0e34\u0e13\u0e11\u0e4c\n\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_5NJQlUvBDp4\" data-date=\"1771580368\" data-video-id=\"5NJQlUvBDp4\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=5NJQlUvBDp4\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i2.ytimg.com\/vi\/5NJQlUvBDp4\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/5NJQlUvBDp4\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/5NJQlUvBDp4\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/5NJQlUvBDp4\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i2.ytimg.com\\\/vi\\\/5NJQlUvBDp4\\\/sddefault.jpg&quot;}\" data-video-id=\"5NJQlUvBDp4\" data-video-title=\"\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 20 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e14\u0e35\u0e40\u0e08\u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e35\u0e40\u0e08\u0e01\u0e34\u0e4a\u0e1f\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c 20 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e14\u0e35\u0e40\u0e08\u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e35\u0e40\u0e08\u0e01\u0e34\u0e4a\u0e1f \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49 \ud83c\udf99\ufe0f\u2728\n\n\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\n\ud83d\udcfb \u0e17\u0e32\u0e07\u0e04\u0e25\u0e37\u0e48\u0e19 FM 99.50 MHz \u0e27\u0e34\u0e17\u0e22\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f\n\ud83d\udce1 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e27\u0e34\u0e17\u0e22\u0e38 R-Radio Network\n\n\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22 : \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1b\u0e25\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\n\n#\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n#\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\n#\u0e27\u0e34\u0e17\u0e22\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\n#RRadioNetwork\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_JGgsum1WqRI\" data-date=\"1770285464\" data-video-id=\"JGgsum1WqRI\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=JGgsum1WqRI\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i3.ytimg.com\/vi\/JGgsum1WqRI\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JGgsum1WqRI\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JGgsum1WqRI\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JGgsum1WqRI\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JGgsum1WqRI\\\/sddefault.jpg&quot;}\" data-video-id=\"JGgsum1WqRI\" data-video-title=\"\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e14\u0e35\u0e40\u0e08\u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e35\u0e40\u0e08\u0e01\u0e34\u0e4a\u0e1f\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e14\u0e35\u0e40\u0e08\u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e35\u0e40\u0e08\u0e01\u0e34\u0e4a\u0e1f \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e44\u0e14\u0e49 \ud83c\udf99\ufe0f\u2728\n\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\n\ud83d\udcfb \u0e17\u0e32\u0e07\u0e04\u0e25\u0e37\u0e48\u0e19 FM 99.50 MHz \u0e27\u0e34\u0e17\u0e22\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f\n\ud83d\udce1 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e27\u0e34\u0e17\u0e22\u0e38 R-Radio Network\n\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22 : \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1b\u0e25\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\n#\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n#\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\n#\u0e27\u0e34\u0e17\u0e22\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\n#RRadioNetwork\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_fKKogAR8B2M\" data-date=\"1769403138\" data-video-id=\"fKKogAR8B2M\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=fKKogAR8B2M\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i3.ytimg.com\/vi\/fKKogAR8B2M\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/fKKogAR8B2M\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/fKKogAR8B2M\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/fKKogAR8B2M\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/fKKogAR8B2M\\\/sddefault.jpg&quot;}\" data-video-id=\"fKKogAR8B2M\" data-video-title=\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e20\u0e32\u0e29\u0e35\u0e23\u0e48\u0e27\u0e21\u0e0a\u0e33\u0e23\u0e30 \u0e20\u0e32\u0e29\u0e35\u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83d\udce2 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e20\u0e32\u0e29\u0e35\n\u0e23\u0e48\u0e27\u0e21\u0e0a\u0e33\u0e23\u0e30 \u0e20\u0e32\u0e29\u0e35\u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \ud83d\udc99\n\n\ud83c\udfe0 \u0e20\u0e32\u0e29\u0e35\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\n\n\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e20\u0e32\u0e29\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\n\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\n\ud83d\udcc6 \u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2569\n\n\ud83d\udcb3 \u0e01\u0e23\u0e13\u0e35\u0e04\u0e48\u0e32\u0e20\u0e32\u0e29\u0e35\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 3,000 \u0e1a\u0e32\u0e17\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\n\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 31 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2569 \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 3 \u0e07\u0e27\u0e14\n\n\u0e07\u0e27\u0e14\u0e17\u0e35\u0e48 1 : \u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19\n\n\u0e07\u0e27\u0e14\u0e17\u0e35\u0e48 2 : \u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21\n\n\u0e07\u0e27\u0e14\u0e17\u0e35\u0e48 3 : \u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\n\n\u26a0\ufe0f \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e48\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\n\n\ud83e\udea7 \u0e20\u0e32\u0e29\u0e35\u0e1b\u0e49\u0e32\u0e22\n\n\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e1b\u0e49\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\n\ud83d\udcc6 \u0e15\u0e49\u0e2d\u0e07\u0e22\u0e37\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e35\u0e19\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35\n\u0e2b\u0e23\u0e37\u0e2d \u0e20\u0e32\u0e22\u0e43\u0e19 15 \u0e27\u0e31\u0e19 \u0e19\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\n\n\u26a0\ufe0f \u0e44\u0e21\u0e48\u0e22\u0e37\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e01\u0e33\u0e2b\u0e19\u0e14\n\u27a4 \u0e40\u0e2a\u0e35\u0e22\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 10 \u0e02\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e1b\u0e49\u0e32\u0e22\n\u26a0\ufe0f \u0e44\u0e21\u0e48\u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e29\u0e35\u0e20\u0e32\u0e22\u0e43\u0e19\u0e01\u0e33\u0e2b\u0e19\u0e14\n\u27a4 \u0e40\u0e2a\u0e35\u0e22\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 2 \u0e15\u0e48\u0e2d\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e1b\u0e49\u0e32\u0e22\n\n\ud83e\uddfe \u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07 \u0e46\n\n\ud83d\uddd1\ufe0f \u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e19\u0e02\u0e22\u0e30\u0e21\u0e39\u0e25\u0e1d\u0e2d\u0e22\n\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e19\u0e02\u0e22\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\n\ud83d\udcc6 \u0e0a\u0e33\u0e23\u0e30\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49 \u2013 30 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2569\n\n\ud83d\udcc4 \u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2d\u0e37\u0e48\u0e19 \u0e46\n\n\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e21\u0e48 : \u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\n\n\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e40\u0e14\u0e34\u0e21 : \u0e22\u0e37\u0e48\u0e19\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e48\u0e2d\u0e19\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2a\u0e34\u0e49\u0e19\u0e2d\u0e32\u0e22\u0e38\n\n\ud83d\udccd \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e29\u0e35\u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\n\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e01\u0e2d\u0e07\u0e04\u0e25\u0e31\u0e07\n\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 (\u0e2d\u0e32\u0e04\u0e32\u0e23 One Stop Service)\n\ud83d\udd58 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e40\u0e27\u0e25\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\n\n\ud83d\udcde \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\n\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c 054-340104 \u0e15\u0e48\u0e2d 146\n\n\ud83c\udf10 \u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-Service)\n\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n\ud83d\udc49 www.tasaban-maemoh.go.th\n\n\ud83d\ude4f \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e20\u0e32\u0e29\u0e35\n\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e43\u0e2b\u0e49\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e04\u0e23\u0e31\u0e1a \ud83d\udc99\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_Ow8S9B_LYao\" data-date=\"1760096783\" data-video-id=\"Ow8S9B_LYao\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=Ow8S9B_LYao\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i4.ytimg.com\/vi\/Ow8S9B_LYao\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/Ow8S9B_LYao\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/Ow8S9B_LYao\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/Ow8S9B_LYao\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/Ow8S9B_LYao\\\/sddefault.jpg&quot;}\" data-video-id=\"Ow8S9B_LYao\" data-video-title=\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e2a\u0e37\u0e1a\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e40\u0e17\u0e42\u0e27\u0e42\u0e23\u0e2b\u0e13\u0e30 2568\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83d\udcf8 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e2a\u0e37\u0e1a\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e40\u0e17\u0e42\u0e27\u0e42\u0e23\u0e2b\u0e13\u0e30 2568\n\u0e13 \u0e27\u0e31\u0e14\u0e23\u0e31\u0e15\u0e19\u0e04\u0e39\u0e2b\u0e32 (\u0e16\u0e49\u0e33\u0e1c\u0e32\u0e01\u0e25\u0e49\u0e27\u0e22) \u0e2b\u0e25\u0e31\u0e07\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e1e\u0e23\u0e23\u0e29\u0e32 \ud83c\udf15\n\u2728 \u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e07\u0e14\u0e07\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u2728\n#\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e40\u0e17\u0e42\u0e27 #\u0e27\u0e31\u0e14\u0e23\u0e31\u0e15\u0e19\u0e04\u0e39\u0e2b\u0e32 #\u0e16\u0e49\u0e33\u0e1c\u0e32\u0e01\u0e25\u0e49\u0e27\u0e22 #\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 #\u0e01\u0e1f\u0e1c\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 #\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_JDTdi61eNgw\" data-date=\"1758638520\" data-video-id=\"JDTdi61eNgw\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=JDTdi61eNgw\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i3.ytimg.com\/vi\/JDTdi61eNgw\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JDTdi61eNgw\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JDTdi61eNgw\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JDTdi61eNgw\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/JDTdi61eNgw\\\/sddefault.jpg&quot;}\" data-video-id=\"JDTdi61eNgw\" data-video-title=\"\u0e41\u0e2a\u0e14\u0e07\u0e21\u0e38\u0e17\u0e34\u0e15\u0e32\u0e08\u0e34\u0e15 \u2764\ufe0f\u0e41\u0e14\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e2d\u0e32\u0e22\u0e38\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e21\u0e38\u0e17\u0e34\u0e15\u0e32\u0e08\u0e34\u0e15 \u2764\ufe0f\n\u0e41\u0e14\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e2d\u0e32\u0e22\u0e38\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49\n\n\ud83d\udc68\u200d\ud83d\udcbc \u0e1b\u0e25\u0e31\u0e14\u0e19\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e48\u0e27\u0e07\u0e44\u0e18\u0e2a\u0e07 \u0e1b\u0e25\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n\u0e42\u0e2d\u0e19 ( \u0e22\u0e49\u0e32\u0e22 ) \u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1b\u0e25\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 ( \u0e19\u0e31\u0e01\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e25\u0e32\u0e07 ) \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2563 \n\n\ud83d\ude97 \u0e19\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e21\u0e35 \u0e04\u0e33\u0e43\u0e2a \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e2d\u0e07\u0e0a\u0e48\u0e32\u0e07\n\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07\u0e15\u0e32\u0e21\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e2d\u0e07\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2547 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e22\u0e38\u0e04\u0e23\u0e1a 60 \u0e1b\u0e35 \u0e41\u0e25\u0e30 \u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\n\n\ud83e\uddf9 \u0e19\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e07 \u0e40\u0e01\u0e35\u0e4b\u0e22\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e04\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e02\u0e22\u0e30 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e2f\n\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07\u0e15\u0e32\u0e21\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e23\u0e16\u0e02\u0e22\u0e30 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e2f \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2554 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e22\u0e38\u0e04\u0e23\u0e1a 60 \u0e1b\u0e35 \u0e41\u0e25\u0e30 \u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e49\u0e32\u0e07 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568 ( \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 )\n\n\ud83d\udc90 \u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e25\u0e49\u0e27\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e25\u0e30 \u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e33\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e15\u0e25\u0e2d\u0e14\u0e44\u0e1b\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_b2DQ8x5Pmfk\" data-date=\"1757830157\" data-video-id=\"b2DQ8x5Pmfk\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=b2DQ8x5Pmfk\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i3.ytimg.com\/vi\/b2DQ8x5Pmfk\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/b2DQ8x5Pmfk\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/b2DQ8x5Pmfk\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/b2DQ8x5Pmfk\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/b2DQ8x5Pmfk\\\/sddefault.jpg&quot;}\" data-video-id=\"b2DQ8x5Pmfk\" data-video-title=\"\u0e1f\u0e31\u0e07 &quot;\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19&quot;\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 12 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83c\udf99\ufe0f \u0e1f\u0e31\u0e07\u0e01\u0e31\u0e19 ! \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23&quot;\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19&quot;\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 12 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2568 \u0e40\u0e27\u0e25\u0e32 13.00 - 15.00 \u0e19. \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\n\ud83d\udccc \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22: \u0e14\u0e35\u0e40\u0e08\u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e08\u0e31\u0e01\u0e1a\u0e34\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1b\u0e25\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \n\ud83d\udd57 \u0e2d\u0e22\u0e48\u0e32\u0e1e\u0e25\u0e32\u0e14! \ud83c\udf1f \u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19!\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_6pxrcqFelMg\" data-date=\"1755586865\" data-video-id=\"6pxrcqFelMg\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=6pxrcqFelMg\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i3.ytimg.com\/vi\/6pxrcqFelMg\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/6pxrcqFelMg\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/6pxrcqFelMg\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/6pxrcqFelMg\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/6pxrcqFelMg\\\/sddefault.jpg&quot;}\" data-video-id=\"6pxrcqFelMg\" data-video-title=\"\u0e1f\u0e31\u0e07 &quot;\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19&quot;\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48 19 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83c\udf99\ufe0f \u0e1f\u0e31\u0e07\u0e01\u0e31\u0e19 ! \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23&quot;\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19&quot;\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48 19 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 11.00 - 12.00 \u0e19. \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\n\ud83d\udccc \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22: \u0e14\u0e35\u0e40\u0e08\u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e08\u0e31\u0e01\u0e1a\u0e34\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1b\u0e25\u0e31\u0e14\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \n\ud83d\udd57 \u0e2d\u0e22\u0e48\u0e32\u0e1e\u0e25\u0e32\u0e14! \ud83c\udf1f \u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19!\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_tKWyepvJF94\" data-date=\"1754994629\" data-video-id=\"tKWyepvJF94\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=tKWyepvJF94\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i1.ytimg.com\/vi\/tKWyepvJF94\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i1.ytimg.com\\\/vi\\\/tKWyepvJF94\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i1.ytimg.com\\\/vi\\\/tKWyepvJF94\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i1.ytimg.com\\\/vi\\\/tKWyepvJF94\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i1.ytimg.com\\\/vi\\\/tKWyepvJF94\\\/sddefault.jpg&quot;}\" data-video-id=\"tKWyepvJF94\" data-video-title=\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e41\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 12 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568 \u0e40\u0e27\u0e25\u0e32 09.30 \u0e19. \u0e13 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e1f\u0e1c. \u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e22\u0e0a\u0e38\u0e15\u0e34\u0e40\u0e14\u0e0a \u0e21\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e41\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e13\u0e31\u0e0a\u0e0a\u0e32 \u0e21\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07\/\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e35\u0e22\u0e07\n\n\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e25\u0e32 200,000 \u0e15\u0e31\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\n#\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07 #\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 #\u0e27\u0e31\u0e19\u0e41\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 #\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 #\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e25\u0e32 #\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 #\u0e23\u0e48\u0e27\u0e21\u0e41\u0e23\u0e07\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 #12\u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e212568\n\n\u0e02\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22 : \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_nFC_Eaw65Ho\" data-date=\"1754994463\" data-video-id=\"nFC_Eaw65Ho\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=nFC_Eaw65Ho\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i3.ytimg.com\/vi\/nFC_Eaw65Ho\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/nFC_Eaw65Ho\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/nFC_Eaw65Ho\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/nFC_Eaw65Ho\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i3.ytimg.com\\\/vi\\\/nFC_Eaw65Ho\\\/sddefault.jpg&quot;}\" data-video-id=\"nFC_Eaw65Ho\" data-video-title=\"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e16\u0e27\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e1e\u0e23\u0e30\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83c\udf38 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e16\u0e27\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \ud83c\udf38\n\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568 \u0e19\u0e32\u0e22\u0e1e\u0e19\u0e21\u0e1e\u0e23 \u0e15\u0e38\u0e49\u0e22\u0e01\u0e32\u0e28 \u0e19\u0e32\u0e22\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e32\u0e22\u0e01\u0e01\u0e34\u0e48\u0e07\u0e01\u0e32\u0e0a\u0e32\u0e14\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e19\u0e32\u0e22\u0e18\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 \u0e0a\u0e38\u0e21\u0e28\u0e23\u0e35 \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e20\u0e34\u0e01\u0e29\u0e38\u0e2a\u0e07\u0e06\u0e4c\n\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e33\u0e1b\u0e48\u0e32\u0e41\u0e14\u0e14 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e27\u0e31\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e0a\u0e19\u0e21\u0e1e\u0e23\u0e23\u0e29\u0e32 12 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568\n\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e19\u0e49\u0e2d\u0e21\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e08\u0e07\u0e23\u0e31\u0e01\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e15\u0e48\u0e32\u0e07\u0e15\u0e31\u0e49\u0e07\u0e08\u0e34\u0e15\u0e2d\u0e18\u0e34\u0e29\u0e10\u0e32\u0e19 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e17\u0e23\u0e07\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e1e\u0e25\u0e32\u0e19\u0e32\u0e21\u0e31\u0e22\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e23\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e48\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e1b\u0e27\u0e07\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e15\u0e25\u0e2d\u0e14\u0e44\u0e1b\n\u0e02\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22 : \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div><div class=\"sby_item  sby_new sby_transition\" id=\"sby_UC-0aF2-1CLYcEVv6G3K_Kfw_3HJakGk1xuE\" data-date=\"1754635035\" data-video-id=\"3HJakGk1xuE\">\n    <div class=\"sby_inner_item\">\n        <div class=\"sby_video_thumbnail_wrap sby_item_video_thumbnail_wrap\">\n            <a class=\"sby_video_thumbnail sby_item_video_thumbnail\" href=\"https:\/\/www.youtube.com\/watch?v=3HJakGk1xuE\" target=\"_blank\" rel=\"noopener\" data-full-res=\"https:\/\/i4.ytimg.com\/vi\/3HJakGk1xuE\/maxresdefault.jpg\" data-img-src-set=\"{&quot;120&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/3HJakGk1xuE\\\/default.jpg&quot;,&quot;320&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/3HJakGk1xuE\\\/mqdefault.jpg&quot;,&quot;480&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/3HJakGk1xuE\\\/hqdefault.jpg&quot;,&quot;640&quot;:&quot;https:\\\/\\\/i4.ytimg.com\\\/vi\\\/3HJakGk1xuE\\\/sddefault.jpg&quot;}\" data-video-id=\"3HJakGk1xuE\" data-video-title=\"\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e23\u0e2d\u0e1a\u0e23\u0e31\u0e49\u0e27\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2f\">\n                <img decoding=\"async\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/plugins\/feeds-for-youtube\/img\/placeholder.png\" alt=\"\ud83d\udcdf\u0e0a\u0e27\u0e19\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \ud83d\udcfc \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e23\u0e2d\u0e1a\u0e23\u0e31\u0e49\u0e27\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2f \n\ud83d\udd34\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e0a\u0e21\n- \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c http:\/\/www.tasaban-maemoh.go.th\/radio\n- \u0e40\u0e1e\u0e08 Facebook : \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \n- \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n\ud83d\udd34\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\n- \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e27\u0e34\u0e17\u0e22\u0e38 R-Radio Network FM 99.50 MHz \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e1f\u0e1c.\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30\n\u23f1\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23 10.00 - 12.00 \u0e19.\n\u23f1\u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c 13.00 - 15.00 \u0e19.\n\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22 : \u0e41\u0e2d\u0e21\u0e1b\u0e4c \u0e08\u0e31\u0e01\u0e1a\u0e34\u0e13\u0e11\u0e4c\n\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\">\n\n                <div class=\"sby_thumbnail_hover sby_item_video_thumbnail_hover\">\n                    <div class=\"sby_thumbnail_hover_inner\">\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"sby_play_btn\" >\n                        <span class=\"sby_play_btn_bg\"><\/span>\n                        <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>                    <\/div>\n                                <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n            <\/a>\n\n                    <\/div>\n    <\/div>\n<\/div>    <\/div>\n    \n\t<div class=\"sby_footer\">\n\n    <button type=\"button\" aria-label=\"Load more content\" class=\"sby_load_btn\"  >\n        <span class=\"sby_btn_text\" >Load More...<\/span>\n        <span class=\"sby_loader sby_hidden\" style=\"background-color: rgb(255, 255, 255);\"><\/span>\n    <\/button>\n\n    <span \n        class=\"sby_follow_btn\" \n            >\n        <a \n            href=\"https:\/\/www.youtube.com\/channel\/UC-0aF2-1CLYcEVv6G3K_Kfw\/\"\n             \n            target=\"_blank\" \n            rel=\"noopener\"\n        >\n            <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fab\" data-icon=\"youtube\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-youtube fa-w-18\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" class=\"\"><\/path><\/svg>            <span  >\n                Subscribe            <\/span>\n        <\/a>\n    <\/span>\n<\/div>\n    \n\t\n<\/div>\n\n<style type=\"text\/css\">body #sb_youtube_sbyUC0aF21CLYcEVv6G3KKfw12 .sby_caption_wrap .sby_caption { font-size: 13px !important}body #sb_youtube_sbyUC0aF21CLYcEVv6G3KKfw12[data-videostyle=boxed] .sby_items_wrap .sby_item .sby_inner_item { background-color: #ffffff !important}<\/style>\n<p><a href=\"http:\/\/www.tasaban-maemoh.go.th\/radio\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5493 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio.jpg\" alt=\"\" width=\"2263\" height=\"812\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio.jpg 2263w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio-660x237.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio-768x276.jpg 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2018\/11\/PR-radio-840x301.jpg 840w\" sizes=\"auto, (max-width: 2263px) 100vw, 2263px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17427 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/04\/pot.jpg\" alt=\"\" width=\"1640\" height=\"924\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/04\/pot.jpg 1640w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/04\/pot-648x365.jpg 648w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/04\/pot-840x473.jpg 840w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/04\/pot-768x433.jpg 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2024\/04\/pot-1536x865.jpg 1536w\" sizes=\"auto, (max-width: 1640px) 100vw, 1640px\" \/><\/p>\n\n<table id=\"tablepress-15\" class=\"tablepress tablepress-id-15\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><a href=\"http:\/\/www.tasaban-maemoh.go.th\/radio\/?page_id=414\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-338 size-full\" src=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19.jpg\" alt=\"\" width=\"385\" height=\"280\" \/><\/a><\/th><th class=\"column-2\"><a href=\"http:\/\/www.tasaban-maemoh.go.th\/radio\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-338 size-full\" src=\"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2020\/07\/3\u0e40\u0e01\u0e47\u0e1a3\u0e42\u0e23\u0e04\u0e43\u0e2b\u0e21\u0e48.jpg\" alt=\"\" width=\"385\" height=\"280\" \/><\/a><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1f\u0e31\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e1e\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e30\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e21\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e21\u0e32\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e02\u0e49\u0e2d\u0e04\u0e33\u0e16\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e43\u0e14\u0e16\u0e39\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e34\u0e14 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e2d\u0e48\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e04\u0e33\u0e16\u0e32\u0e21\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e02\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e19\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e17\u0e35\u0e48\u0e17\u0e48\u0e32\u0e19\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e04\u0e33\u0e16\u0e32\u0e21\u0e19\u0e31\u0e49\u0e19<\/td><td class=\"column-2\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e2a\u0e1b\u0e2d\u0e15\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c 3 \u0e40\u0e01\u0e47\u0e1a 3 \u0e42\u0e23\u0e04 \u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e1b\u0e27\u0e14\u0e02\u0e49\u0e2d\u0e22\u0e38\u0e07\u0e25\u0e32\u0e22 \u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e2d\u0e2d\u0e01 \u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e0b\u0e34\u0e01\u0e32<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-15 from cache -->\n<p><a href=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/prnews\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7346 size-full\" src=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/News-List.jpg\" alt=\"\" width=\"1196\" height=\"89\" srcset=\"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/News-List.jpg 1196w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/News-List-660x49.jpg 660w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/News-List-768x57.jpg 768w, https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-content\/uploads\/2019\/11\/News-List-840x63.jpg 840w\" sizes=\"auto, (max-width: 1196px) 100vw, 1196px\" \/><\/a><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u00a0&gt; \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 &gt; \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 &gt; &hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"class_list":["post-1582","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/comments?post=1582"}],"version-history":[{"count":380,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/revisions"}],"predecessor-version":[{"id":27113,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/pages\/1582\/revisions\/27113"}],"wp:attachment":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/media?parent=1582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}