{"id":13754,"date":"2022-06-27T14:31:23","date_gmt":"2022-06-27T07:31:23","guid":{"rendered":"http:\/\/www.tasaban-maemoh.go.th\/tbmm\/?p=13754"},"modified":"2022-06-30T14:32:24","modified_gmt":"2022-06-30T07:32:24","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-78","status":"publish","type":"post","link":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/13754\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e48\u0e07\u0e19\u0e49\u0e33\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e21\u0e07\u0e04\u0e25 \u0e2b\u0e21\u0e39\u0e48 10"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-13754","post","type-post","status-publish","format-standard","hentry","category-procurement-results"],"_links":{"self":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/posts\/13754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/comments?post=13754"}],"version-history":[{"count":1,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/posts\/13754\/revisions"}],"predecessor-version":[{"id":13756,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/posts\/13754\/revisions\/13756"}],"wp:attachment":[{"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/media?parent=13754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/categories?post=13754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tasaban-maemoh.go.th\/tbmm\/wp-json\/wp\/v2\/tags?post=13754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}